{"id":38573,"date":"2026-09-01T12:10:46","date_gmt":"2026-09-01T10:10:46","guid":{"rendered":"https:\/\/www.omni-biotic.com\/de-de\/?page_id=38573"},"modified":"2026-09-02T08:16:51","modified_gmt":"2026-09-02T06:16:51","slug":"magenta-month","status":"publish","type":"page","link":"https:\/\/www.omni-biotic.com\/de-de\/magenta-month\/","title":{"rendered":"Magenta Month"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"38573\" class=\"elementor elementor-38573\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49043c2 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default\" data-id=\"49043c2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1835247\" data-id=\"1835247\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8991457 elementor-nav-menu__align-end elementor-nav-menu--dropdown-mobile elementor-nav-menu--stretch elementor-nav-menu__text-align-center elementor-widget__width-auto elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"8991457\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-8991457\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-240\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/kontakt\/\" class=\"elementor-item\">Kontakt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13267\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmberater-finder\/\" class=\"elementor-item\">Darmberater-Finder<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27751\"><a href=\"https:\/\/www.allergosan.com\/de\/downloadcenter\/\" class=\"elementor-item\" target=\"_blank\" rel=\"noopener\">Downloadcenter<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23000\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/newsletter\/\" class=\"elementor-item\">Newsletter<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23002\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/power-team\/\" class=\"elementor-item\">POWERTEAM<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-8991457\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-240\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/kontakt\/\" class=\"elementor-item\" tabindex=\"-1\">Kontakt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13267\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmberater-finder\/\" class=\"elementor-item\" tabindex=\"-1\">Darmberater-Finder<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27751\"><a href=\"https:\/\/www.allergosan.com\/de\/downloadcenter\/\" class=\"elementor-item\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\">Downloadcenter<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23000\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/newsletter\/\" class=\"elementor-item\" tabindex=\"-1\">Newsletter<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23002\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/power-team\/\" class=\"elementor-item\" tabindex=\"-1\">POWERTEAM<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9581606 elementor-widget__width-auto language-nav-button elementor-widget elementor-widget-image\" data-id=\"9581606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/06\/flag-of-germany.svg\" class=\"attachment-large size-large wp-image-38049\" alt=\"flag of germany\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2920743 elementor-widget__width-auto language-nav-button elementor-widget elementor-widget-text-editor\" data-id=\"2920743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AT<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6975413 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-height-default\" data-id=\"6975413\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1c84907\" data-id=\"1c84907\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a64d31 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"2a64d31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.omni-biotic.com\/de-de\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"131\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/260729_MagentaMonth-Logo_OB_2000px-300x131.png\" class=\"attachment-medium size-medium wp-image-38575\" alt=\"\" srcset=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/260729_MagentaMonth-Logo_OB_2000px-300x131.png 300w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/260729_MagentaMonth-Logo_OB_2000px-1024x446.png 1024w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/260729_MagentaMonth-Logo_OB_2000px-768x334.png 768w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/260729_MagentaMonth-Logo_OB_2000px-1536x669.png 1536w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/260729_MagentaMonth-Logo_OB_2000px-1920x836.png 1920w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/260729_MagentaMonth-Logo_OB_2000px.png 2001w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-578bf8a elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"578bf8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bef0fed elementor-nav-menu__align-end elementor-nav-menu--dropdown-none elementor-widget__width-auto elementor-widget elementor-widget-nav-menu\" data-id=\"bef0fed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-bef0fed\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-66\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/\" data-show-popup=\"181\" class=\"elementor-item\">\u00dcber uns<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-68\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/was-ist-omni-biotic\/\" class=\"elementor-sub-item\">Was ist OMNi-BiOTiC\u00ae?<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32917\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/stufenkonzept\/\" class=\"elementor-sub-item\">Unser 3-Stufen-Konzept<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-32600\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/\" class=\"elementor-sub-item\">Institut AllergoSan<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-72\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/kompetenzzentrum\/\" class=\"elementor-sub-item\">Kompetenzzentrum<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-74\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/anita-frauwallner\/\" class=\"elementor-sub-item\">Prof. Anita Frauwallner<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-36211\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/30-jahre-jubilaeum\/\" class=\"elementor-sub-item\">30 Jahre OMNi-BiOTiC\u00ae<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-34430\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/charity\/\" class=\"elementor-sub-item\">Charity<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-35137\"><a href=\"https:\/\/www.allergosan.com\/de\/karriere\/\" class=\"elementor-sub-item\" target=\"_blank\" rel=\"noopener\">Karriere<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20454\"><a href=\"https:\/\/www.allergosan.com\/at\/presse\/\" class=\"elementor-sub-item\" target=\"_blank\" rel=\"noopener\">Presse<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30202\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/nachhaltigkeit\/\" class=\"elementor-sub-item\">Nachhaltigkeit am Institut AllergoSan<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-80\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/kontakt\/\" class=\"elementor-sub-item\">Kontakt<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20453\"><a href=\"https:\/\/www.allergosan.com\/de\/karriere\/\" class=\"elementor-sub-item\" target=\"_blank\" rel=\"noopener\">Karriere<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-20458\"><a href=\"https:\/\/www.darmakademie.com\/at\/\" class=\"elementor-sub-item\" target=\"_blank\" rel=\"noopener\">Fortbildungen<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20455\"><a href=\"https:\/\/www.darmakademie.com\/de\/veranstaltungsreihe\/fachakademie\/\" class=\"elementor-sub-item\" target=\"_blank\" rel=\"noopener\">Pr\u00e4senz Fachakademie<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20457\"><a href=\"https:\/\/www.darmakademie.com\/de\/veranstaltungsreihe\/fachakademie-digital\/\" class=\"elementor-sub-item\" target=\"_blank\" rel=\"noopener\">Digitale Fachakademie<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20456\"><a href=\"https:\/\/www.darmakademie.com\/de\/veranstaltungsreihe\/laien-webinare\/\" class=\"elementor-sub-item\" target=\"_blank\" rel=\"noopener\">Webinare<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-88\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/blog\/\" class=\"elementor-sub-item\">Blog<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-23348\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/forschung-entwicklung\/\" class=\"elementor-sub-item\">Forschung &amp; Entwicklung<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-94\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/forschung-entwicklung\/qualitaetskriterien\/\" class=\"elementor-sub-item\">Qualit\u00e4tskriterien<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-96\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/forschung-entwicklung\/studienspiegel\/\" class=\"elementor-sub-item\">Studienspiegel<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30904\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/forschung-entwicklung\/stimmen-aus-der-wissenschaft\/\" class=\"elementor-sub-item\">Stimmen aus der Wissenschaft<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"super-fake-megamenu__products menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-98\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/\" data-show-popup=\"203\" class=\"elementor-item\">Produkte<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-100\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic\/\" class=\"elementor-sub-item\">OMNi-BiOTiC\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38534\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic-fibre\/\" class=\"elementor-sub-item\">OMNi-BiOTiC\u00ae FiBRE<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37902\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic-vital\/\" class=\"elementor-sub-item\">OMNi-BiOTiC\u00ae ViTAL<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-34065\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic-skin\/\" class=\"elementor-sub-item\">OMNi-BiOTiC SKiN\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38512\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic-vet\/\" class=\"elementor-sub-item\">OMNi-BiOTiC\u00ae VET<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-104\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-power\/\" class=\"elementor-sub-item\">OMNi-POWER\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-106\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/meta-care\/\" class=\"elementor-sub-item\">META-CARE\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-108\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/caricol-brand\/\" class=\"elementor-sub-item\">Caricol\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-28699\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/dr-med-schuetze\/\" class=\"elementor-sub-item\">Dr. med. Sch\u00fctze\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-112\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/weitere-marken\/\" class=\"elementor-sub-item\">Weitere Marken<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-114\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produktberater\/\" class=\"elementor-sub-item\">OMNi-BiOTiC\u00ae-Berater<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12855\"><a href=\"#\" data-show-popup=\"217\" class=\"elementor-item elementor-item-anchor\">Darmgesundheit<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-20613\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/\" class=\"elementor-sub-item\">Gesundheitszentrale Darm<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-28722\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/mikrobiomanalyse\/\" class=\"elementor-sub-item\">Mikrobiomanalyse<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-120\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/probiotika\/\" class=\"elementor-sub-item\">Probiotika<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-122\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/praebiotika\/\" class=\"elementor-sub-item\">Pr\u00e4biotika<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-124\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darmmikrobiom\/\" class=\"elementor-sub-item\">Darmmikrobiom<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-126\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darmbakterien\/\" class=\"elementor-sub-item\">Darmbakterien<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-128\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darmkur\/\" class=\"elementor-sub-item\">Darmkur<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-130\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darm-hirn-achse\/\" class=\"elementor-sub-item\">Darm-Hirn-Achse<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-132\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darm-leber-achse\/\" class=\"elementor-sub-item\">Darm-Leber-Achse<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-134\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darmflora\/\" class=\"elementor-sub-item\">Darmflora<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23657\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/haustier\/\" class=\"elementor-sub-item\">Tiergesundheit<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-138\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/\" class=\"elementor-sub-item\">Einflussbereiche des Darms<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-35043\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/biohacking\/\" class=\"elementor-sub-item\">Biohacking<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-140\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/immunsystem\/\" class=\"elementor-sub-item\">Immunsystem<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-146\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/mundmikrobiom\/\" class=\"elementor-sub-item\">Mund-Mikrobiom<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-144\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/stress\/\" class=\"elementor-sub-item\">Stress, Verdauung und depressive Verstimmung<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-148\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/wunschfigur\/\" class=\"elementor-sub-item\">Wunschfigur<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37708\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/frauengesundheit\/\" class=\"elementor-sub-item\">Frauengesundheit<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-142\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/scheidenflora\/\" class=\"elementor-sub-item\">Scheidenflora<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-150\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/schwangerschaft-stillzeit\/\" class=\"elementor-sub-item\">Schwangerschaft &amp; Stillzeit<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32796\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/wechseljahre-menopause\/\" class=\"elementor-sub-item\">Wechseljahre &amp; Menopause<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23722\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/blog\/\" class=\"elementor-sub-item\">Blog<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"super-fake-megamenu__bowel2 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-154\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/\" data-show-popup=\"268\" class=\"elementor-item\">Darmbeschwerden<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-23710\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/\" class=\"elementor-sub-item\">Darmbeschwerden<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-156\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/allergie\/\" class=\"elementor-sub-item\">Allergie<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-160\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/leaky-gut\/\" class=\"elementor-sub-item\">Leaky Gut<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-162\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/reizdarm\/\" class=\"elementor-sub-item\">Reizdarm<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-164\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/ced\/\" class=\"elementor-sub-item\">Chronisch entz\u00fcndliche Darmerkrankungen (CED)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-170\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/blaehbauch-blaehungen\/\" class=\"elementor-sub-item\">Bl\u00e4hungen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-172\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/durchfall\/\" class=\"elementor-sub-item\">Durchfall<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-174\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/verstopfung\/\" class=\"elementor-sub-item\">Verstopfung<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23721\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/blog\/\" class=\"elementor-sub-item\">Blog<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-24496\"><a href=\"https:\/\/shop.omni-biotic.com\/de-de\/collections\/alle-produkte\" class=\"elementor-item\">Shop<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-bef0fed\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-66\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/\" data-show-popup=\"181\" class=\"elementor-item\" tabindex=\"-1\">\u00dcber uns<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-68\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/was-ist-omni-biotic\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Was ist OMNi-BiOTiC\u00ae?<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32917\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/stufenkonzept\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Unser 3-Stufen-Konzept<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-32600\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Institut AllergoSan<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-72\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/kompetenzzentrum\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Kompetenzzentrum<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-74\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/anita-frauwallner\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Prof. Anita Frauwallner<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-36211\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/30-jahre-jubilaeum\/\" class=\"elementor-sub-item\" tabindex=\"-1\">30 Jahre OMNi-BiOTiC\u00ae<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-34430\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/charity\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Charity<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-35137\"><a href=\"https:\/\/www.allergosan.com\/de\/karriere\/\" class=\"elementor-sub-item\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\">Karriere<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20454\"><a href=\"https:\/\/www.allergosan.com\/at\/presse\/\" class=\"elementor-sub-item\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\">Presse<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30202\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/nachhaltigkeit\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Nachhaltigkeit am Institut AllergoSan<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-80\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/kontakt\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Kontakt<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20453\"><a href=\"https:\/\/www.allergosan.com\/de\/karriere\/\" class=\"elementor-sub-item\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\">Karriere<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-20458\"><a href=\"https:\/\/www.darmakademie.com\/at\/\" class=\"elementor-sub-item\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\">Fortbildungen<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20455\"><a href=\"https:\/\/www.darmakademie.com\/de\/veranstaltungsreihe\/fachakademie\/\" class=\"elementor-sub-item\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\">Pr\u00e4senz Fachakademie<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20457\"><a href=\"https:\/\/www.darmakademie.com\/de\/veranstaltungsreihe\/fachakademie-digital\/\" class=\"elementor-sub-item\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\">Digitale Fachakademie<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-20456\"><a href=\"https:\/\/www.darmakademie.com\/de\/veranstaltungsreihe\/laien-webinare\/\" class=\"elementor-sub-item\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\">Webinare<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-88\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/blog\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Blog<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-23348\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/forschung-entwicklung\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Forschung &amp; Entwicklung<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-94\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/forschung-entwicklung\/qualitaetskriterien\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Qualit\u00e4tskriterien<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-96\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/forschung-entwicklung\/studienspiegel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Studienspiegel<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30904\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/forschung-entwicklung\/stimmen-aus-der-wissenschaft\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Stimmen aus der Wissenschaft<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"super-fake-megamenu__products menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-98\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/\" data-show-popup=\"203\" class=\"elementor-item\" tabindex=\"-1\">Produkte<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-100\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic\/\" class=\"elementor-sub-item\" tabindex=\"-1\">OMNi-BiOTiC\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38534\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic-fibre\/\" class=\"elementor-sub-item\" tabindex=\"-1\">OMNi-BiOTiC\u00ae FiBRE<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37902\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic-vital\/\" class=\"elementor-sub-item\" tabindex=\"-1\">OMNi-BiOTiC\u00ae ViTAL<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-34065\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic-skin\/\" class=\"elementor-sub-item\" tabindex=\"-1\">OMNi-BiOTiC SKiN\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38512\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-biotic-vet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">OMNi-BiOTiC\u00ae VET<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-104\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/omni-power\/\" class=\"elementor-sub-item\" tabindex=\"-1\">OMNi-POWER\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-106\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/meta-care\/\" class=\"elementor-sub-item\" tabindex=\"-1\">META-CARE\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-108\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/caricol-brand\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Caricol\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-28699\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/dr-med-schuetze\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Dr. med. Sch\u00fctze\u00ae<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-112\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produkte\/weitere-marken\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Weitere Marken<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-114\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/produktberater\/\" class=\"elementor-sub-item\" tabindex=\"-1\">OMNi-BiOTiC\u00ae-Berater<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12855\"><a href=\"#\" data-show-popup=\"217\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Darmgesundheit<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-20613\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gesundheitszentrale Darm<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-28722\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/mikrobiomanalyse\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mikrobiomanalyse<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-120\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/probiotika\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Probiotika<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-122\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/praebiotika\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pr\u00e4biotika<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-124\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darmmikrobiom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Darmmikrobiom<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-126\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darmbakterien\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Darmbakterien<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-128\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darmkur\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Darmkur<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-130\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darm-hirn-achse\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Darm-Hirn-Achse<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-132\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darm-leber-achse\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Darm-Leber-Achse<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-134\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/darmflora\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Darmflora<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23657\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/gesundheitszentrale-darm\/haustier\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Tiergesundheit<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-138\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Einflussbereiche des Darms<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-35043\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/biohacking\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Biohacking<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-140\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/immunsystem\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Immunsystem<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-146\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/mundmikrobiom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mund-Mikrobiom<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-144\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/stress\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Stress, Verdauung und depressive Verstimmung<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-148\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/wunschfigur\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wunschfigur<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37708\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/frauengesundheit\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Frauengesundheit<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-142\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/scheidenflora\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Scheidenflora<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-150\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/schwangerschaft-stillzeit\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Schwangerschaft &amp; Stillzeit<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32796\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmgesundheit\/einflussbereiche-des-darms\/wechseljahre-menopause\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wechseljahre &amp; Menopause<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23722\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/blog\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Blog<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"super-fake-megamenu__bowel2 menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-154\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/\" data-show-popup=\"268\" class=\"elementor-item\" tabindex=\"-1\">Darmbeschwerden<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-23710\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Darmbeschwerden<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-156\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/allergie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Allergie<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-160\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/leaky-gut\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Leaky Gut<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-162\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/reizdarm\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Reizdarm<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-164\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/ced\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chronisch entz\u00fcndliche Darmerkrankungen (CED)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-170\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/blaehbauch-blaehungen\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bl\u00e4hungen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-172\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/durchfall\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Durchfall<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-174\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/darmbeschwerden\/verstopfung\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Verstopfung<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23721\"><a href=\"https:\/\/www.omni-biotic.com\/de-de\/blog\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Blog<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-24496\"><a href=\"https:\/\/shop.omni-biotic.com\/de-de\/collections\/alle-produkte\" class=\"elementor-item\" tabindex=\"-1\">Shop<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59a83e1 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"59a83e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" class=\"icon\" viewBox=\"0 0 18.37 18.36\"><defs><style>.cls-1{fill:#b6185c;}<\/style><\/defs><path class=\"cls-1\" d=\"M18.15,17.08l-5.16-5.16s-.02-.01-.04-.02h0s.05-.09,.08-.13c.25-.31,.47-.64,.67-1,.22-.42,.41-.85,.55-1.31,.21-.69,.33-1.42,.33-2.17s-.12-1.48-.33-2.16c-.14-.46-.33-.9-.55-1.31-.34-.63-.76-1.19-1.26-1.68C11.13,.82,9.31,0,7.3,0,3.28,0,0,3.27,0,7.29s3.28,7.3,7.3,7.3c1.75,0,3.35-.62,4.6-1.64h0s.01,.02,.02,.03l5.16,5.16c.15,.15,.34,.22,.53,.22s.38-.07,.53-.22c.29-.29,.29-.77,0-1.06Zm-10.85-3.99c-3.2,0-5.8-2.6-5.8-5.8S4.1,1.5,7.3,1.5s5.79,2.6,5.79,5.79-2.6,5.8-5.79,5.8Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d36b01 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5d36b01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/shop.omni-biotic.com\/cart\" target=\"_blank\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" viewBox=\"0 0 20 20\"><defs><style>.cls-1{fill:#b6185c;}<\/style><\/defs><path class=\"cls-1\" d=\"M10,15.9c-.28,0-.5-.22-.5-.5v-6.27c0-.28,.22-.5,.5-.5s.5,.22,.5,.5v6.27c0,.28-.22,.5-.5,.5Z\"><\/path><path class=\"cls-1\" d=\"M13.5,15.9s-.05,0-.08,0c-.27-.04-.46-.3-.41-.57l1-6.09c.04-.27,.31-.46,.57-.41,.27,.04,.46,.3,.41,.57l-1,6.09c-.04,.25-.25,.42-.49,.42Z\"><\/path><path class=\"cls-1\" d=\"M6.5,15.9c-.24,0-.45-.17-.49-.42l-1-6.09c-.04-.27,.14-.53,.41-.57,.27-.05,.53,.14,.57,.41l1,6.09c.04,.27-.14,.53-.41,.57-.03,0-.05,0-.08,0Z\"><\/path><path class=\"cls-1\" d=\"M18.57,7.17c-.09-.12-.24-.18-.39-.18h-2.43l-3.35-4.79c-.16-.23-.47-.28-.7-.12-.23,.16-.28,.47-.12,.7l2.95,4.21H5.46l2.95-4.21c.16-.23,.1-.54-.12-.7-.23-.16-.54-.1-.7,.12l-3.35,4.79H1.81c-.15,0-.29,.07-.39,.18-.09,.12-.13,.27-.1,.42l2,9.74c.05,.23,.25,.4,.49,.4h12.37c.24,0,.44-.17,.49-.4l2-9.74c.03-.15,0-.3-.1-.42Zm-2.8,9.56H4.22L2.43,7.98h15.15l-1.79,8.74Z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-369dba2 open-mobile-menu elementor-hidden-desktop\" data-id=\"369dba2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe4264d elementor-hidden-desktop elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"fe4264d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ac51cc3 elementor-hidden-desktop\" data-id=\"ac51cc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06014c4 elementor-widget-tablet__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"06014c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" class=\"icon\" viewBox=\"0 0 18.37 18.36\"><defs><style>.cls-1{fill:#b6185c;}<\/style><\/defs><path class=\"cls-1\" d=\"M18.15,17.08l-5.16-5.16s-.02-.01-.04-.02h0s.05-.09,.08-.13c.25-.31,.47-.64,.67-1,.22-.42,.41-.85,.55-1.31,.21-.69,.33-1.42,.33-2.17s-.12-1.48-.33-2.16c-.14-.46-.33-.9-.55-1.31-.34-.63-.76-1.19-1.26-1.68C11.13,.82,9.31,0,7.3,0,3.28,0,0,3.27,0,7.29s3.28,7.3,7.3,7.3c1.75,0,3.35-.62,4.6-1.64h0s.01,.02,.02,.03l5.16,5.16c.15,.15,.34,.22,.53,.22s.38-.07,.53-.22c.29-.29,.29-.77,0-1.06Zm-10.85-3.99c-3.2,0-5.8-2.6-5.8-5.8S4.1,1.5,7.3,1.5s5.79,2.6,5.79,5.79-2.6,5.8-5.79,5.8Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b921f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b921f2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9003515\" data-id=\"9003515\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-438db95 e-con-full obcs none e-flex e-con e-parent\" data-id=\"438db95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-137cb15 elementor-widget elementor-widget-li-widgets--hero\" data-id=\"137cb15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--hero.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"li-hero\">\n    <div class=\"li-hero__band\">\n        <div class=\"li-hero__copy\">\n            <div class=\"ob-section-head ob-section-head--stacked\">\n                <div class=\"ob-section-head__group\">\n                                            <span class=\"ob-eyebrow\">Magenta Month. Ein ganzer Monat im Zeichen Ihrer Frauengesundheit.<\/span>\n                                                                <div class=\"ob-display\">Stark in jeder Lebensphase.<\/div>\n                                    <\/div>\n                                    <p class=\"ob-lead ob-section-head__lead\">Erhalten Sie Rabatt auf ausgew\u00e4hlte Produkte, fundiertes Wissen, Beratung von Expertinnen f\u00fcr unterschiedliche Lebensphasen und eine Community, in der Frauen offen sprechen k\u00f6nnen.<\/p>\n                            <\/div>\n\n            \n                            <div class=\"li-hero__actions\">\n                                            <a class=\"ob-btn ob-btn--primary\" href=\"#profitieren\">Jetzt profitieren <svg class=\"ob-arrow\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" aria-hidden=\"true\"><path d=\"M5 12h14M13 6l6 6-6 6\"\/><\/svg><\/a>\n                                                        <\/div>\n                    <\/div>\n\n        <div class=\"li-hero__visual\">\n            <div class=\"li-hero__frame\">\n                <img decoding=\"async\" width=\"800\" height=\"416\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/magenta-month-frauen-1024x532.png\" class=\"attachment-large size-large\" alt=\"Magenta Month\" srcset=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/magenta-month-frauen-1024x532.png 1024w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/magenta-month-frauen-300x156.png 300w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/magenta-month-frauen-768x399.png 768w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/magenta-month-frauen.png 1329w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>                            <\/div>\n\n                    <\/div>\n    <\/div>\n\n            <div class=\"li-hero__trust\">\n            <div class=\"ob-stat-row ob-stat-row--band\">\n                                                        <div class=\"ob-stat ob-stat--featured\">\n                        <span class=\"ob-stat__num ob-stat__num--solid\">150+<\/span>\n                        <span class=\"ob-stat__body\">\n                            <strong class=\"ob-stat__label\">wissenschaftliche Studien<\/strong>\n                            <small class=\"ob-stat__note\">Studien zu Produkten aus unserem Sortiment<\/small>\n                        <\/span>\n                    <\/div>\n                                                        <div class=\"ob-stat\">\n                        <span class=\"ob-stat__num\">70<\/span>\n                        <span class=\"ob-stat__body\">\n                            <strong class=\"ob-stat__label\">Forschungspartner<\/strong>\n                            <small class=\"ob-stat__note\">Universit\u00e4ten und Institutionen weltweit<\/small>\n                        <\/span>\n                    <\/div>\n                                                        <div class=\"ob-stat\">\n                        <span class=\"ob-stat__num\">30+<\/span>\n                        <span class=\"ob-stat__body\">\n                            <strong class=\"ob-stat__label\">Jahre Forschung zum Leben im Darm<\/strong>\n                            <small class=\"ob-stat__note\">am Institut AllergoSan<\/small>\n                        <\/span>\n                    <\/div>\n                            <\/div>\n        <\/div>\n    <\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8977ea6 obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"8977ea6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9abc8c6 elementor-widget elementor-widget-li-widgets--feature-advice\" data-id=\"9abc8c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--feature-advice.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-advice-stage\">\n    <section class=\"li-advice ob-scheme ob-scheme--magenta\">\n        <div class=\"li-advice__media\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"734\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof.anita-frauwallner-1024x940.jpg\" class=\"li-advice__img\" alt=\"\" srcset=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof.anita-frauwallner-1024x940.jpg 1024w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof.anita-frauwallner-300x275.jpg 300w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof.anita-frauwallner-768x705.jpg 768w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof.anita-frauwallner.jpg 1229w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>        <\/div>\n\n        <div class=\"li-advice__copy\">\n            <div class=\"ob-section-head ob-section-head--stacked\">\n                <div class=\"ob-section-head__group\">\n                                            <span class=\"ob-eyebrow ob-eyebrow--ondark\">Von einer Frau gegr\u00fcndet. F\u00fcr starke Frauen weitergedacht.<\/span>\n                                                                <h2 class=\"ob-h2\">Unsere Geschichte<\/h2>\n                                    <\/div>\n                                    <p class=\"ob-lead ob-section-head__lead\">Prof. Anita Frauwallner, Gr\u00fcnderin und CEO des Institut AllergoSan, forscht mit Leidenschaft f\u00fcr die Gesundheit von Frauen und hat mit dieser Vision den Grundstein f\u00fcr OMNi-BiOTiC\u00ae gelegt. Als Frau an der Spitze von Forschung und Unternehmen ist es ihr ein zentrales Anliegen, Frauen sowohl in der Wissenschaft als auch im eigenen Betrieb sichtbar zu machen und zu f\u00f6rdern \u2013 getragen von dem Grundgedanken, Gesundheit f\u00fcr alle Menschen zug\u00e4nglich zu machen. \nBis heute wird unser Unternehmen ma\u00dfgeblich von Frauen gestaltet: in der Forschung und Entwicklung, in der wissenschaftlichen Beratung, in verantwortungsvollen F\u00fchrungspositionen und in vielen weiteren Bereichen.<\/p>\n                            <\/div>\n\n                            <div class=\"li-advice__actions\">\n                    \n                                                                                <\/div>\n                    <\/div>\n    <\/section>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b53a839 obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"b53a839\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0390544 elementor-widget elementor-widget-menu-anchor\" data-id=\"0390544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"profitieren\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc553da obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"dc553da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3347a63 elementor-widget elementor-widget-li-widgets--cards-team\" data-id=\"3347a63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--cards-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"li-cg li-cg--team ob-section\">\n    <div class=\"ob-section__inner\">\n        <div class=\"li-cg__inner\">\n            <div class=\"ob-section-head\">\n                <div class=\"ob-section-head__group\">\n                                            <span class=\"ob-eyebrow\">So profitieren Sie im Magenta Month<\/span>\n                                                                <h2 class=\"ob-h1\">Von Frauen. F\u00fcr Frauen. Unser Magenta Month.<\/h2>\n                                    <\/div>\n                            <\/div>\n\n                            <div class=\"ob-card-grid\">\n                                                                    <a class=\"ob-card ob-card--tint elementor-repeater-item-910dd5d\" href=\"https:\/\/shop.omni-biotic.com\/collections\/magenta-month\">\n                            <div class=\"ob-card__media\">\n                                                                    <img decoding=\"async\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/aktionsprodukt.png\" alt=\"10 % Rabatt\">\n                                                            <\/div>\n                            <div class=\"ob-card__body\">\n                                                                                                    <h3 class=\"ob-card__title\">10 % Rabatt<\/h3>\n                                                                                                    <p class=\"ob-card__text\">Kaufen Sie 1 Aktionsprodukt und erhalten Sie 10 % darauf<\/p>\n                                                            <\/div>\n                        <\/a>\n                                                                    <a class=\"ob-card ob-card--tint elementor-repeater-item-deeba87\" href=\"https:\/\/shop.omni-biotic.com\/collections\/magenta-month\">\n                            <div class=\"ob-card__media\">\n                                                                    <img decoding=\"async\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/aktionsprodukte.png\" alt=\"20 % Rabatt\">\n                                                            <\/div>\n                            <div class=\"ob-card__body\">\n                                                                                                    <h3 class=\"ob-card__title\">20 % Rabatt<\/h3>\n                                                                                                    <p class=\"ob-card__text\">Kaufen Sie mindestens 2 Aktionsprodukte und erhalten Sie 20 % auf Ihren Einkauf<\/p>\n                                                            <\/div>\n                        <\/a>\n                                                                    <a class=\"ob-card ob-card--tint elementor-repeater-item-60f9ac5\" href=\"https:\/\/kampagne.doc.green\/omnibiotic-k-at#\/\" target=\"_blank\" rel=\"noopener\">\n                            <div class=\"ob-card__media\">\n                                                                    <img decoding=\"async\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/gutschein.png\" alt=\"\u20ac 4,- Gutschein\">\n                                                            <\/div>\n                            <div class=\"ob-card__body\">\n                                                                                                    <h3 class=\"ob-card__title\">\u20ac 4,- Gutschein<\/h3>\n                                                                                                    <p class=\"ob-card__text\">Zus\u00e4tzlich beim Kauf ab 3 Aktionsprodukten in einer Apotheke Ihrer Wahl<\/p>\n                                                            <\/div>\n                        <\/a>\n                                    <\/div>\n\n                                                        <a class=\"ob-link li-cg__more\" href=\"https:\/\/shop.omni-biotic.com\/de-de\/collections\/magenta-month\"><span>Jetzt profitieren<\/span> <svg class=\"ob-arrow ob-arrow--up-right\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" aria-hidden=\"true\"><path d=\"M5 12h14M13 6l6 6-6 6\"\/><\/svg><\/a>\n                                    <\/div>\n    <\/div>\n<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-091086b obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"091086b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e519616 elementor-widget elementor-widget-li-widgets--feature-research\" data-id=\"e519616\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--feature-research.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-research-stage\">\n    <section class=\"li-research ob-scheme ob-scheme--magenta\">\n        <div class=\"li-research__copy\">\n            <div class=\"ob-section-head ob-section-head--stacked\">\n                <div class=\"ob-section-head__group\">\n                                                                <h2 class=\"ob-h2\">Was ist der Magenta Month?<\/h2>\n                                    <\/div>\n                                    <p class=\"ob-lead ob-section-head__lead\">Der Magenta Month steht im Zeichen der Frau. Als Unternehmen besch\u00e4ftigen wir uns seit Jahren intensiv mit Gesundheitsthemen, dem Darm-Mikrobiom und den besonderen Bed\u00fcrfnissen von Frauen in unterschiedlichen Lebensphasen. Die wissenschaftliche Forschung in diesen Bereichen ist ein wesentlicher Bestandteil unserer Arbeit und treibt die Entwicklung unserer Produkte tagt\u00e4glich voran.<\/p>\n                            <\/div>\n\n                            <div class=\"li-research__tags\">\n                                                                        <span class=\"ob-badge ob-badge--label ob-badge--ondark\">Frauengesundheit im Fokus<\/span>\n                                                                                                <span class=\"ob-badge ob-badge--label ob-badge--ondark\">Ausgew\u00e4hlte Produkte mit Rabattvorteil<\/span>\n                                                                                                <span class=\"ob-badge ob-badge--label ob-badge--ondark\">F\u00fcr jede Lebensphase passend<\/span>\n                                                            <\/div>\n            \n                            <div class=\"ob-facts\">\n                                            <div class=\"ob-facts__item\">\n                                                            <b class=\"ob-facts__num\">73 %<\/b>\n                                                        <div class=\"ob-facts__body\">\n                                                                    <strong class=\"ob-facts__title\">Frauenanteil<\/strong>\n                                                                                                    <span class=\"ob-facts__sub\">Am Institut AllergoSan<\/span>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"ob-facts__item\">\n                                                            <b class=\"ob-facts__num\">56 %<\/b>\n                                                        <div class=\"ob-facts__body\">\n                                                                    <strong class=\"ob-facts__title\">Frauen<\/strong>\n                                                                                                    <span class=\"ob-facts__sub\">In F\u00fchrungspositionen<\/span>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"ob-facts__item\">\n                                                            <b class=\"ob-facts__num\">70<\/b>\n                                                        <div class=\"ob-facts__body\">\n                                                                    <strong class=\"ob-facts__title\">Forschungspartner weltweit<\/strong>\n                                                                                                    <span class=\"ob-facts__sub\">Universit\u00e4ten, Kliniken und Forschungseinrichtungen.<\/span>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"ob-facts__item\">\n                                                            <b class=\"ob-facts__num\">30+<\/b>\n                                                        <div class=\"ob-facts__body\">\n                                                                    <strong class=\"ob-facts__title\">Jahre Mikrobiom-Forschung<\/strong>\n                                                                                                    <span class=\"ob-facts__sub\">Wissenschaftliche Pr\u00e4zision seit der Pionierphase.<\/span>\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n            \n            \n                    <\/div>\n\n        <figure class=\"li-research__image\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/forschung-institut-allergosan-1-684x1024.jpg\" class=\"li-research__img\" alt=\"\" srcset=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/forschung-institut-allergosan-1-684x1024.jpg 684w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/forschung-institut-allergosan-1-200x300.jpg 200w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/forschung-institut-allergosan-1-768x1151.jpg 768w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/forschung-institut-allergosan-1.jpg 1024w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/>            \n                    <\/figure>\n    <\/section>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a48b734 obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"a48b734\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08fdae2 elementor-widget elementor-widget-li-widgets--feature-advice\" data-id=\"08fdae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--feature-advice.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-advice-stage\">\n    <section class=\"li-advice ob-scheme ob-scheme--light ob-scheme--tint-3\">\n        <div class=\"li-advice__media\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof-anit-frauwallner-verena-stiegelbauer-ingeborg-klymikuk-frauen-institut-allergosan.jpg\" class=\"li-advice__img\" alt=\"\" srcset=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof-anit-frauwallner-verena-stiegelbauer-ingeborg-klymikuk-frauen-institut-allergosan.jpg 800w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof-anit-frauwallner-verena-stiegelbauer-ingeborg-klymikuk-frauen-institut-allergosan-300x200.jpg 300w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/09\/prof-anit-frauwallner-verena-stiegelbauer-ingeborg-klymikuk-frauen-institut-allergosan-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>        <\/div>\n\n        <div class=\"li-advice__copy\">\n            <div class=\"ob-section-head ob-section-head--stacked\">\n                <div class=\"ob-section-head__group\">\n                                            <span class=\"ob-eyebrow ob-eyebrow--ondark\">Frauen tragen im Institut AllergoSan nicht nur zur Zukunft der Forschung bei \u2013 sie gestalten sie aktiv mit.<\/span>\n                                                                <h2 class=\"ob-h2\">Frauengesundheit sichtbar machen<\/h2>\n                                    <\/div>\n                                    <p class=\"ob-lead ob-section-head__lead\">Der Magenta Month steht f\u00fcr unser Engagement, Frauengesundheit sichtbarer zu machen, wissenschaftlich voranzutreiben und Frauen dabei zu unterst\u00fctzen, sich selbst die Aufmerksamkeit zu schenken, die sie verdienen. Hinter OMNi-BiOTiC\u00ae stehen Frauen, die mit Forschung, Wissen und Leidenschaft Frauengesundheit sichtbar machen.<\/p>\n                            <\/div>\n\n                            <div class=\"li-advice__actions\">\n                    \n                                                                                <\/div>\n                    <\/div>\n    <\/section>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b8ee675 obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"b8ee675\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d3c87c elementor-widget elementor-widget-li-widgets--product-grid\" data-id=\"4d3c87c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--product-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"li-pg ob-section\">\n    <div class=\"ob-section__inner\">\n        <div class=\"li-pg__inner\">\n            <div class=\"ob-section-head\">\n                <div class=\"ob-section-head__group\">\n                                            <span class=\"ob-eyebrow\">Unsere Empfehlungen f\u00fcr Ihre Lebensphase<\/span>\n                                                                <h2 class=\"ob-h1\">Finden Sie Ihre Begleiter.<\/h2>\n                                    <\/div>\n                                    <p class=\"ob-lead ob-section-head__lead\">Jede Lebensphase stellt andere Anforderungen. Hier finden Sie alle Aktionsprodukte sowie unsere Empfehlungen f\u00fcr Ihre individuelle Lebensphase.<\/p>\n                            <\/div>\n\n                    <\/div>\n    <\/div>\n<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ecb3c56 obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"ecb3c56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6ea252 elementor-widget elementor-widget-li-widgets--feature-advice\" data-id=\"a6ea252\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--feature-advice.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-advice-stage\">\n    <section class=\"li-advice ob-scheme ob-scheme--light ob-scheme--tint-2\">\n        <div class=\"li-advice__media\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/05\/medizinisch-wissenschaftliche-beratung-kostenlos-kein-produktverkauf.jpg\" class=\"li-advice__img\" alt=\"\" srcset=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/05\/medizinisch-wissenschaftliche-beratung-kostenlos-kein-produktverkauf.jpg 800w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/05\/medizinisch-wissenschaftliche-beratung-kostenlos-kein-produktverkauf-300x300.jpg 300w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/05\/medizinisch-wissenschaftliche-beratung-kostenlos-kein-produktverkauf-150x150.jpg 150w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/05\/medizinisch-wissenschaftliche-beratung-kostenlos-kein-produktverkauf-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>        <\/div>\n\n        <div class=\"li-advice__copy\">\n            <div class=\"ob-section-head ob-section-head--stacked\">\n                <div class=\"ob-section-head__group\">\n                                            <span class=\"ob-eyebrow ob-eyebrow--ondark\">Sie sind sich noch unsicher, welches Produkt zu Ihnen passt?<\/span>\n                                                                <h2 class=\"ob-h2\">Wir sind f\u00fcr Sie da!<\/h2>\n                                    <\/div>\n                                    <p class=\"ob-lead ob-section-head__lead\">Jede Frau und jede Lebensphase ist anders. Ob Zyklus, Schwangerschaft, Wechseljahre oder einfach das Gef\u00fchl, dass im K\u00f6rper gerade nicht alles im Gleichgewicht ist: Bevor Sie sich f\u00fcr ein Produkt entscheiden, darf gerne noch die eine oder andere Frage gekl\u00e4rt werden. Unser hochqualifiziertes Beratungsteam, bestehend aus \u00c4rzten, Apothekern, Biologen, Ern\u00e4hrungsexperten und Mikrobiologen, steht Ihnen gerne zur Verf\u00fcgung. Gemeinsam finden wir heraus, welche L\u00f6sung am besten zu Ihrer aktuellen Situation passt.<\/p>\n                            <\/div>\n\n                            <div class=\"li-advice__actions\">\n                                                                    <a class=\"ob-btn ob-btn--primary\" href=\"tel:+43316405305%20\">Tel: +43 (0)316 405 305 <svg class=\"ob-arrow ob-arrow--up-right\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" aria-hidden=\"true\"><path d=\"M5 12h14M13 6l6 6-6 6\"\/><\/svg><\/a>\n                    \n                                                                                                    <a class=\"ob-link ob-link--ondark\" href=\"mailto:info@allergosan.com\"><span>info@allergosan.com<\/span> <svg class=\"ob-arrow\" width=\"15\" height=\"15\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" aria-hidden=\"true\"><path d=\"M5 12h14M13 6l6 6-6 6\"\/><\/svg><\/a>\n                                                                                                                            <a class=\"ob-link ob-link--ondark\" href=\"https:\/\/www.omni-biotic.com\/de-de\/ueber-uns\/institut-allergosan\/kontakt\/\"><span>Kontaktformular<\/span> <svg class=\"ob-arrow\" width=\"15\" height=\"15\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" aria-hidden=\"true\"><path d=\"M5 12h14M13 6l6 6-6 6\"\/><\/svg><\/a>\n                                                            <\/div>\n                    <\/div>\n    <\/section>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a53c85 obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"2a53c85\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7091522 elementor-widget elementor-widget-li-widgets--feature-microbiome\" data-id=\"7091522\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--feature-microbiome.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-fm-stage\">\n    <section class=\"li-fm ob-scheme ob-scheme--light ob-scheme--tint-3\">\n        <div class=\"li-fm__media\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/07\/frauen-community-facebook.jpg\" class=\"li-fm__img\" alt=\"Frauen Community\" srcset=\"https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/07\/frauen-community-facebook.jpg 800w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/07\/frauen-community-facebook-300x300.jpg 300w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/07\/frauen-community-facebook-150x150.jpg 150w, https:\/\/www.omni-biotic.com\/de-de\/wp-content\/uploads\/sites\/10\/2026\/07\/frauen-community-facebook-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>                    <\/div>\n\n        <div class=\"li-fm__copy\">\n            <div class=\"ob-section-head ob-section-head--stacked\">\n                <div class=\"ob-section-head__group\">\n                                            <span class=\"ob-eyebrow ob-eyebrow--ondark\">Werden Sie Teil unserer Facebook-Community<\/span>\n                                                                <h2 class=\"ob-h1\">Starke Mitte \u2013 starke Frauen<\/h2>\n                                    <\/div>\n                                    <p class=\"ob-lead ob-section-head__lead\">Wir sind \u00fcberzeugt: Es ist Zeit, offener \u00fcber Frauengesundheit zu sprechen! Deshalb haben wir unsere OMNi-BiOTiC\u00ae-Frauen-Community ins Leben gerufen. \nDenn Wohlbefinden und die untrennbar damit verbundene Selbstf\u00fcrsorge entstehen nicht nur durch Forschung allein, sondern vor allem auch durch den Dialog miteinander.<\/p>\n                            <\/div>\n\n                            <div class=\"ob-feature-card-grid\">\n                                                                    <article class=\"ob-feature-card\">\n                            <span class=\"ob-feature-card__icon\" aria-hidden=\"true\"><i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i><\/span>\n                            <span class=\"ob-feature-card__num\"><\/span>\n                                                            <h3 class=\"ob-feature-card__title\">Evidenzbasierte Informationen<\/h3>\n                                                                                        <p class=\"ob-feature-card__text\">Wissenschaftlich fundiertes Wissen rund um die Frauengesundheit und das Mikrobiom.<\/p>\n                                                    <\/article>\n                                                                    <article class=\"ob-feature-card\">\n                            <span class=\"ob-feature-card__icon\" aria-hidden=\"true\"><i aria-hidden=\"true\" class=\"fas fa-microphone\"><\/i><\/span>\n                            <span class=\"ob-feature-card__num\"><\/span>\n                                                            <h3 class=\"ob-feature-card__title\">Expertinnen-Impulse<\/h3>\n                                                                                        <p class=\"ob-feature-card__text\">Alltagstaugliche Tipps und wertvolle Impulse von unseren Fachberaterinnen f\u00fcr Ihr Wohlbefinden.<\/p>\n                                                    <\/article>\n                                                                    <article class=\"ob-feature-card\">\n                            <span class=\"ob-feature-card__icon\" aria-hidden=\"true\"><i aria-hidden=\"true\" class=\"fas fa-gift\"><\/i><\/span>\n                            <span class=\"ob-feature-card__num\"><\/span>\n                                                            <h3 class=\"ob-feature-card__title\">Geheime Vorteile<\/h3>\n                                                                                        <p class=\"ob-feature-card__text\">Exklusiv f\u00fcr Sie als Community-Mitglied.<\/p>\n                                                    <\/article>\n                                    <\/div>\n            \n                                            <a class=\"ob-link ob-link--ondark\" href=\"https:\/\/www.facebook.com\/groups\/1463581602369241\" target=\"_blank\" rel=\"noopener\"><span>Teil der Community werden<\/span> <svg class=\"ob-arrow\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" aria-hidden=\"true\"><path d=\"M5 12h14M13 6l6 6-6 6\"\/><\/svg><\/a>\n                    <\/div>\n    <\/section>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a69225 obcs none e-flex e-con-boxed e-con e-parent\" data-id=\"7a69225\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f02fd18 elementor-icon-list--layout-inline elementor-mobile-align-center elementor-widget-mobile__width-inherit elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f02fd18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.omni-biotic.com\/de-de\/impressum\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Impressum<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.allergosan.com\/de\/datenschutzerklaerung\/\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Datenschutz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/shop.omni-biotic.com\/de-de\/policies\/terms-of-service\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">AGB<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f2b77e elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"5f2b77e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00a9 Copyright 2026 OMNi-BiOTiC\u00ae\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>AT Magenta Month. Ein ganzer Monat im Zeichen Ihrer Frauengesundheit. Stark in jeder Lebensphase. Erhalten Sie Rabatt auf ausgew\u00e4hlte Produkte, fundiertes Wissen, Beratung von Expertinnen f\u00fcr unterschiedliche Lebensphasen und eine Community, in der Frauen offen sprechen k\u00f6nnen. Jetzt profitieren 150+ wissenschaftliche Studien Studien zu Produkten aus unserem Sortiment 70 Forschungspartner Universit\u00e4ten und Institutionen weltweit 30+ [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":38576,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-38573","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/pages\/38573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/comments?post=38573"}],"version-history":[{"count":7,"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/pages\/38573\/revisions"}],"predecessor-version":[{"id":38636,"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/pages\/38573\/revisions\/38636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/media\/38576"}],"wp:attachment":[{"href":"https:\/\/www.omni-biotic.com\/de-de\/wp-json\/wp\/v2\/media?parent=38573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}